{"id":424,"count":1,"description":"","link":"http:\/\/blogs.terrorware.com\/geoff\/tag\/hotnewmexicanspunkshow\/","name":"hotnewmexicans.punk.show","slug":"hotnewmexicanspunkshow","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/blogs.terrorware.com\/geoff\/wp-json\/wp\/v2\/tags\/424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/blogs.terrorware.com\/geoff\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/blogs.terrorware.com\/geoff\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/blogs.terrorware.com\/geoff\/wp-json\/wp\/v2\/posts?tags=424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}